{"id":18,"date":"2010-08-25T20:09:03","date_gmt":"2010-08-25T20:09:03","guid":{"rendered":"http:\/\/www.fidastreviso.it\/b\/?p=18"},"modified":"2010-08-25T20:09:03","modified_gmt":"2010-08-25T20:09:03","slug":"la-gita","status":"publish","type":"post","link":"https:\/\/www.fidastreviso.it\/b\/2010\/08\/la-gita\/","title":{"rendered":"La gita?"},"content":{"rendered":"<p>Cari amici, si avvicina il periodo in cui di solito collochiamo la gita sociale: purtroppo quest&#8217;anno<strong> non la faremo<\/strong>, preferiamo tenerci pronti per il prossimo congresso fidas a Parma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cari amici, si avvicina il periodo in cui di solito collochiamo la gita sociale: purtroppo quest&#8217;anno non la faremo, preferiamo tenerci pronti per il prossimo congresso fidas a Parma.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.fidastreviso.it\/b\/wp-json\/wp\/v2\/posts\/18"}],"collection":[{"href":"https:\/\/www.fidastreviso.it\/b\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fidastreviso.it\/b\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fidastreviso.it\/b\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fidastreviso.it\/b\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":0,"href":"https:\/\/www.fidastreviso.it\/b\/wp-json\/wp\/v2\/posts\/18\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fidastreviso.it\/b\/wp-json\/wp\/v2\/media?parent=18"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fidastreviso.it\/b\/wp-json\/wp\/v2\/categories?post=18"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fidastreviso.it\/b\/wp-json\/wp\/v2\/tags?post=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}